{"id":767,"date":"2020-11-18T10:51:40","date_gmt":"2020-11-18T10:51:40","guid":{"rendered":"http:\/\/www.teatrodonizetti.it\/?page_id=767"},"modified":"2023-06-14T15:43:24","modified_gmt":"2023-06-14T13:43:24","slug":"i-sostenitori-del-restauro","status":"publish","type":"page","link":"https:\/\/www.teatrodonizetti.it\/it\/i-sostenitori-del-restauro\/","title":{"rendered":"I sostenitori del restauro"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><h5><em><span style=\"font-weight: 400;\">L\u2019Amministrazione Comunale e la Fondazione Teatro Donizetti restituiscono il Teatro rinnovato alla Citt\u00e0 con un particolare ringraziamento a chi ha contribuito al restauro.<\/span><\/em><\/h5>\n<h2>MEMBRI BENEMERITI<\/h2>\n<ul>\n<li>A2A S.p.A<\/li>\n<li>Allianz S.p.A.<\/li>\n<li>ATB Azienda Trasporti Bergamo<\/li>\n<li>Banca Popolare di Bergamo S.p.A.<\/li>\n<li>Brembo S.p.A.<\/li>\n<li>Camera di Commercio Industria Artigianato e Agricoltura di Bergamo<\/li>\n<li>Confindustria Bergamo \u2013 Servizi Confindustria Bergamo<\/li>\n<li>Fondazione Cariplo<\/li>\n<li>Fondazione Credito Bergamasco<\/li>\n<li>Gewiss S.p.A.<\/li>\n<li>Ministero dei Beni e delle Attivit\u00e0 Culturali<\/li>\n<li>Luciana e Gianni Radici<\/li>\n<li>Regione Lombardia<\/li>\n<li>SACBO S.p.A. Aeroporto di Bergamo<\/li>\n<li>Gruppo Sanpellegrino \u2013 Nestl\u00e9 Waters<\/li>\n<li>Societ\u00e0 Italiana Acetilene e Derivati S.I.A.D. S.p.A.<\/li>\n<\/ul>\n<h2>MEMBRI SOSTENITORI<\/h2>\n<ul>\n<li>Carvico S.p.A.<\/li>\n<li>Cav. Uff. Claudio Curnis<\/li>\n<li>Corpo Palchisti Teatro Donizetti<\/li>\n<li>Itema Group<\/li>\n<li>Letizia e Isabella Ghisalberti<\/li>\n<li>Montello S.p.A.<\/li>\n<li>Uniacque S.p.A.<\/li>\n<\/ul>\n<h2>MEMBRI ORDINARI<\/h2>\n<ul>\n<li>3V Green Eagle S.p.A.<\/li>\n<li>ANCE Bergamo<\/li>\n<li>Automha S.p.A.<\/li>\n<li>Bonaldi Motori S.p.A.<\/li>\n<li>Chimiver Panseri S.p.A.<\/li>\n<li>DIACHEM<\/li>\n<li>Fecs Partecipazioni S.p.A.<\/li>\n<li>Fidelitas S.p.A.<\/li>\n<li>ICTeam S.p.A.<\/li>\n<li>IRE-OMBA S.p.A.<\/li>\n<li>Lovato Electric S.p.A.<\/li>\n<li>Nuova Demi S.p.A dei Fratelli Doneda<\/li>\n<li>Rossini Trading S.p.A.<\/li>\n<li>Studio Berta Nembrini Colombini &amp; Associati<\/li>\n<li>Zanetti S.p.A.<\/li>\n<\/ul>\n<h5><em><span style=\"font-weight: 400;\">Si ringraziano inoltre i palchisti proprietari e tutti coloro che hanno contribuito alla ristrutturazione del Teatro Donizetti attraverso \u201cArt Bonus\u201d o attraverso l\u2019iniziativa \u201cMattone digitale\u201d.<\/span><\/em><\/h5>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"folder":[],"class_list":["post-767","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/pages\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/comments?post=767"}],"version-history":[{"count":0,"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/pages\/767\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.teatrodonizetti.it\/it\/wp-json\/wp\/v2\/folder?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}